{"id":7851,"date":"2023-02-22T16:36:00","date_gmt":"2023-02-22T16:36:00","guid":{"rendered":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/?page_id=7851"},"modified":"2025-03-20T12:24:04","modified_gmt":"2025-03-20T12:24:04","slug":"modern-slavery-act-2015-statement-2","status":"publish","type":"page","link":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/modern-slavery-act-2015-statement-2\/","title":{"rendered":"\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"7851\" class=\"elementor elementor-7851\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6173a76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6173a76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a1548b\" data-id=\"1a1548b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40e6303 elementor-widget elementor-widget-heading\" data-id=\"40e6303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u06cc\u06a9\u0679 (2015) \u0628\u06cc\u0627\u0646 2025-26<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e5728e elementor-widget elementor-widget-text-editor\" data-id=\"0e5728e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u0644\u06cc\u0633\u0679\u0631\u060c \u0644\u06cc\u0633\u0679\u0631 \u0634\u0627\u0626\u0631\u060c \u0627\u0648\u0631 \u0631\u0679\u0644\u06cc\u0646\u0688 <\/strong><strong>\u0627\u0646\u0679\u06cc\u06af\u0631\u06cc\u0679\u0688 \u06a9\u06cc\u0626\u0631 \u0628\u0648\u0631\u0688 (ICB)<\/strong><\/p><p><strong>\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u06cc\u06a9\u0679 (2015) \u0628\u06cc\u0627\u0646 2025-26\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/strong><\/p><p>Leicester, Leicestershire, and Rutland Integrated Care Board (LLR ICB) \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u06cc\u06a9\u0679 2015 \u06a9\u06d2 \u062a\u0642\u0627\u0636\u0648\u06ba \u06a9\u0648 \u0644\u0627\u06af\u0648 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u067e\u0631\u0639\u0632\u0645 \u06c1\u06d2 \u0627\u0648\u0631 \u06cc\u06c1 \u0628\u06cc\u0627\u0646 \u0627\u0646 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u06a9\u0627 \u062a\u0639\u06cc\u0646 \u06a9\u0631\u062a\u0627 \u06c1\u06d2 \u062c\u0648 LLR ICB \u0627\u0633 \u0628\u0627\u062a \u06a9\u0648 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u0679\u06be\u0627 \u0631\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u06c1\u0645\u0627\u0631\u06cc \u062a\u0646\u0638\u06cc\u0645 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0633\u06d2 \u0622\u0632\u0627\u062f \u06c1\u06d2\u06d4<\/p><p>\u0627\u06cc\u06a9\u0679 \u06cc\u06c1 \u0628\u062a\u0627\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 36 \u0645\u0644\u06cc\u0646 \u06cc\u0627 \u0627\u0633 \u0633\u06d2 \u0632\u06cc\u0627\u062f\u06c1 \u06a9\u0627 \u06a9\u0627\u0631\u0648\u0628\u0627\u0631 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06cc \u062a\u0646\u0638\u06cc\u0645\u0648\u06ba \u06a9\u0648 \u0627\u0646 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0633\u0627\u0644\u0627\u0646\u06c1 \u0631\u067e\u0648\u0631\u0679 \u06a9\u0631\u0646\u0627 \u06c1\u0648\u06af\u06cc \u062c\u0648 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0645\u0627\u0644\u06cc \u0633\u0627\u0644 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0627\u0679\u06be\u0627\u0626\u06d2 \u06c1\u06cc\u06ba \u062a\u0627\u06a9\u06c1 \u06cc\u06c1 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u06cc\u0627 \u062c\u0627 \u0633\u06a9\u06d2 \u06a9\u06c1 \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u0627\u0646 \u06a9\u06d2 \u0627\u067e\u0646\u06d2 \u06a9\u0627\u0631\u0648\u0628\u0627\u0631 \u06cc\u0627 \u0627\u0646 \u06a9\u06cc \u0633\u067e\u0644\u0627\u0626\u06cc \u0686\u06cc\u0646 \u0645\u06cc\u06ba \u0646\u06c1\u06cc\u06ba \u06c1\u0648 \u0631\u06c1\u06cc \u06c1\u06d2\u06d4<\/p><p>\u0627\u06cc\u06a9\u0679 \u06a9\u0627 \u0633\u06cc\u06a9\u0634\u0646 54 \u0627\u0646 \u062a\u0646\u0638\u06cc\u0645\u0648\u06ba \u0633\u06d2 \u0645\u0637\u0627\u0644\u0628\u06c1 \u06a9\u0631\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0648\u06c1 \u0627\u06cc\u06a9 \u0628\u06cc\u0627\u0646 \u062a\u06cc\u0627\u0631 \u06a9\u0631\u06cc\u06ba \u0627\u0648\u0631 \u0634\u0627\u0626\u0639 \u06a9\u0631\u06cc\u06ba \u062c\u0648 \u0627\u0633 \u0645\u0627\u0644\u06cc \u0633\u0627\u0644 \u06a9\u06d2 \u062f\u0648\u0631\u0627\u0646 \u0627\u0646\u06c1\u0648\u06ba \u0646\u06d2 \u0627\u0679\u06be\u0627\u0626\u06d2 \u06c1\u06cc\u06ba \u0627\u0633 \u0628\u0627\u062a \u06a9\u0648 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06a9\u06c1 \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u0646\u06c1\u06cc\u06ba \u06c1\u0648 \u0631\u06c1\u06cc \u06c1\u06d2:<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u06a9\u06cc\u0627 \u06c1\u06d2\u061f<\/strong><\/p><p>\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u06a9\u06d2 \u062c\u0631\u0645 \u0645\u06cc\u06ba \u06a9\u0633\u06cc \u06a9\u0648 \u063a\u0644\u0627\u0645\u06cc \u06cc\u0627 \u063a\u0644\u0627\u0645\u06cc \u06a9\u0627 \u0646\u0634\u0627\u0646\u06c1 \u0628\u0646\u0627\u0646\u0627\u060c \u062c\u0628\u0631\u06cc \u06cc\u0627 \u062c\u0628\u0631\u06cc \u0645\u0634\u0642\u062a\u060c \u0628\u0634\u0645\u0648\u0644 \u0686\u0627\u0626\u0644\u0688 \u0644\u06cc\u0628\u0631\u060c \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af\u060c \u0627\u06a9\u062b\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u062d\u0642\u0648\u0642 \u06a9\u06d2 \u0642\u0627\u0646\u0648\u0646\u060c \u0631\u0648\u0632\u06af\u0627\u0631 \u06a9\u06d2 \u0642\u0627\u0646\u0648\u0646 \u0627\u0648\u0631 \u0635\u062d\u062a \u0627\u0648\u0631 \u062d\u0641\u0627\u0638\u062a \u06a9\u06d2 \u0636\u0648\u0627\u0628\u0637 \u06a9\u06cc \u062e\u0644\u0627\u0641 \u0648\u0631\u0632\u06cc\u060c \u0633\u062e\u062a \u0627\u0648\u0631 \u063a\u06cc\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0633\u0644\u0648\u06a9\u060c \u0627\u0648\u0631 \u0627\u0633\u062a\u062d\u0635\u0627\u0644\u06cc \u0637\u0648\u0631 \u067e\u0631 \u06a9\u0645 \u062a\u0646\u062e\u0648\u0627\u06c1 \u0627\u0648\u0631 \u0637\u0648\u06cc\u0644 \u06af\u06be\u0646\u0679\u0648\u06ba.<\/p><p>\u06a9\u0648\u0626\u06cc \u063a\u0644\u0627\u0645\u06cc \u0645\u06cc\u06ba \u06c1\u06d2 \u0627\u06af\u0631 \u0648\u06c1 \u06c1\u06cc\u06ba:<\/p><ul><li>\u06cc\u0627 \u062a\u0648 \u0632\u0628\u0631\u062f\u0633\u062a\u06cc\u060c \u0630\u06c1\u0646\u06cc \u06cc\u0627 \u062c\u0633\u0645\u0627\u0646\u06cc \u062f\u06be\u0645\u06a9\u06cc \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u06a9\u0627\u0645 \u06a9\u0631\u0646\u06d2 \u067e\u0631 \u0645\u062c\u0628\u0648\u0631 \u06a9\u06cc\u0627 \u062c\u0627\u062a\u0627 \u06c1\u06d2\u06d4<\/li><li>\u0630\u06c1\u0646\u06cc \u06cc\u0627 \u062c\u0633\u0645\u0627\u0646\u06cc \u0628\u062f\u0633\u0644\u0648\u06a9\u06cc\u060c \u06cc\u0627 \u0628\u062f\u0633\u0644\u0648\u06a9\u06cc \u06a9\u06d2 \u062e\u0637\u0631\u06d2 \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 &#039;\u0622\u062c\u0631&#039; \u06a9\u06cc \u0645\u0644\u06a9\u06cc\u062a \u06cc\u0627 \u06a9\u0646\u0679\u0631\u0648\u0644<\/li><li>\u0627\u062c\u0646\u0627\u0633 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u0633\u0644\u0648\u06a9 \u06a9\u0631\u06a9\u06d2 \u06cc\u0627 &#039;\u062c\u0627\u0626\u06cc\u062f\u0627\u062f&#039; \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631 \u062e\u0631\u06cc\u062f \u0648 \u0641\u0631\u0648\u062e\u062a \u06a9\u0631\u06a9\u06d2 \u063a\u06cc\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc<\/li><li>\u062c\u0633\u0645\u0627\u0646\u06cc \u0637\u0648\u0631 \u067e\u0631 \u0645\u062d\u062f\u0648\u062f \u06cc\u0627 \u0627\u0646 \u06a9\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc\u0648\u06ba \u0627\u0648\u0631 \u0637\u0631\u06cc\u0642\u06c1 \u06a9\u0627\u0631 \u06a9\u06cc \u0622\u0632\u0627\u062f\u06cc \u067e\u0631 \u063a\u06cc\u0631 \u0642\u0627\u0646\u0648\u0646\u06cc \u067e\u0627\u0628\u0646\u062f\u06cc\u0627\u06ba \u0644\u06af\u0627\u0626\u06cc \u06af\u0626\u06cc \u06c1\u06cc\u06ba<\/li><\/ul><p>\u0644\u06cc\u0633\u0679\u0631\u060c \u0644\u06cc\u0633\u0679\u0631 \u0634\u0627\u0626\u0631\u060c \u0627\u0648\u0631 \u0631\u0679\u0644\u06cc\u0646\u0688 \u06a9\u06cc \u0622\u0628\u0627\u062f\u06cc \u06a9\u06d2 \u0644\u06cc\u06d2 \u0635\u062d\u062a \u06a9\u06cc \u062f\u06cc\u06a9\u06be \u0628\u06be\u0627\u0644 \u06a9\u06cc \u062e\u062f\u0645\u0627\u062a \u06a9\u0648 \u06a9\u0645\u06cc\u0634\u0646 \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u0642\u0627\u0645\u06cc \u0631\u06c1\u0646\u0645\u0627 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631\u060c \u0627\u0648\u0631 \u0627\u06cc\u06a9 \u0622\u062c\u0631 \u06a9\u06d2 \u0637\u0648\u0631 \u067e\u0631\u060c LLR ICB \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u06d2 \u0637\u0631\u06cc\u0642\u0648\u06ba \u06a9\u0648 \u0631\u0648\u06a9\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u067e\u0646\u06cc \u0648\u0627\u0628\u0633\u062a\u06af\u06cc\u060c \u0627\u0648\u0631 \u06a9\u0648\u0634\u0634\u0648\u06ba \u06a9\u06d2 \u0633\u0644\u0633\u0644\u06d2 \u0645\u06cc\u06ba \u062f\u0631\u062c \u0630\u06cc\u0644 \u0628\u06cc\u0627\u0646 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4 \u0633\u067e\u0644\u0627\u0626\u06cc \u0686\u06cc\u0646 \u0627\u0648\u0631 \u0631\u0648\u0632\u06af\u0627\u0631 \u06a9\u06d2 \u0637\u0631\u06cc\u0642\u06d2\u06d4<\/p><p><strong>\u00a0<\/strong><\/p><p><strong>\u06c1\u0645\u0627\u0631\u06d2 \u0631\u0648\u0632\u06af\u0627\u0631 \u06a9\u06d2 \u0637\u0631\u06cc\u0642\u0648\u06ba \u06a9\u06d2 \u0630\u0631\u06cc\u0639\u06d2 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u06a9\u0648 \u0631\u0648\u06a9\u0646\u0627<\/strong><\/p><p>LLR ICB \u06a9\u06d2 \u067e\u0627\u0633 \u062e\u0637\u0631\u06d2 \u06a9\u06cc \u062a\u0634\u062e\u06cc\u0635 \u06a9\u06d2 \u0645\u0636\u0628\u0648\u0637 \u0639\u0645\u0644 \u06c1\u06cc\u06ba \u062c\u0648 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0633\u06d2 \u0645\u062a\u0639\u0644\u0642 \u06a9\u0633\u06cc \u0628\u06be\u06cc \u0645\u0639\u0627\u0645\u0644\u06d2 \u0633\u06d2 \u0646\u0645\u0679\u0646\u06d2 \u0645\u06cc\u06ba \u06c1\u0645\u0627\u0631\u06d2 \u0646\u0642\u0637\u06c1 \u0646\u0638\u0631 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u06cc\u0642\u06cc\u0646 \u062f\u06c1\u0627\u0646\u06cc \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 \u06c1\u0645\u0627\u0631\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc\u0627\u06ba \u062c\u06cc\u0633\u06d2 \u06a9\u06c1 \u06c1\u0631\u0627\u0633\u0627\u06ba \u06a9\u0631\u0646\u06d2 \u0627\u0648\u0631 \u063a\u0646\u0688\u06c1 \u06af\u0631\u062f\u06cc \u06a9\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc\u060c \u0634\u06a9\u0627\u06cc\u062a \u06a9\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc \u0627\u0648\u0631 \u0628\u0648\u0644\u0646\u06d2 \u06a9\u06cc \u0622\u0632\u0627\u062f\u06cc \u06a9\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc \u06c1\u0645\u0627\u0631\u06d2 \u0645\u0644\u0627\u0632\u0645\u06cc\u0646 \u06a9\u0648 \u06a9\u0627\u0645 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0646\u0627\u0642\u0635 \u0637\u0631\u06cc\u0642\u0648\u06ba \u06cc\u0627 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0633\u06d2 \u0645\u062a\u0639\u0644\u0642 \u06a9\u0633\u06cc \u0628\u06be\u06cc \u0645\u0639\u0627\u0645\u0644\u06d2 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u062a\u0634\u0648\u06cc\u0634 \u06a9\u0627 \u0627\u0638\u06c1\u0627\u0631 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u06cc\u06a9 \u0627\u0636\u0627\u0641\u06cc \u067e\u0644\u06cc\u0679 \u0641\u0627\u0631\u0645 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u06d4<\/p><p>LLR ICB \u0627\u0633 \u0628\u0627\u062a \u06a9\u0648 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1 \u06c1\u0645\u0627\u0631\u06cc \u0628\u06be\u0631\u062a\u06cc \u06a9\u06d2 \u0639\u0645\u0644 \u0645\u0636\u0628\u0648\u0637 \u06c1\u06cc\u06ba \u0627\u0633 \u0628\u0627\u062a \u06a9\u0648 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u0646\u0627 \u062c\u0627\u0631\u06cc \u0631\u06a9\u06be\u06d2 \u06af\u0627 \u06a9\u06c1 \u0628\u06be\u0631\u062a\u06cc \u06a9\u06d2 \u0645\u062d\u0641\u0648\u0638 \u0627\u0635\u0648\u0644\u0648\u06ba (ICB \u06a9\u06cc \u0628\u06be\u0631\u062a\u06cc \u0633\u0644\u06cc\u06a9\u0634\u0646 \u0627\u0648\u0631 \u0627\u0646\u0688\u06a9\u0634\u0646 \u067e\u0627\u0644\u06cc\u0633\u06cc) \u067e\u0631 \u0639\u0645\u0644 \u067e\u06cc\u0631\u0627 \u06c1\u0648\u06ba\u06d4 \u0627\u0633 \u0645\u06cc\u06ba \u0634\u0646\u0627\u062e\u062a \u06a9\u06cc \u062c\u0627\u0646\u0686\u060c \u0648\u0631\u06a9 \u067e\u0631\u0645\u0679 \u0627\u0648\u0631 \u0645\u062c\u0631\u0645\u0627\u0646\u06c1 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u06a9\u06d2 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0633\u062e\u062a \u062a\u0642\u0627\u0636\u06d2 \u0634\u0627\u0645\u0644 \u06c1\u06cc\u06ba\u06d4<\/p><p>\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u06a9\u06d2 \u062e\u0627\u062a\u0645\u06d2 \u0645\u06cc\u06ba \u0627\u067e\u0646\u0627 \u062d\u0635\u06c1 \u0688\u0627\u0644\u0646\u06d2 \u06a9\u0627 \u0639\u0632\u0645 \u06c1\u0645\u0627\u0631\u06cc \u062d\u0641\u0627\u0638\u062a \u06a9\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc\u0648\u06ba \u0627\u0648\u0631 \u0637\u0631\u06cc\u0642\u06c1 \u06a9\u0627\u0631 \u0633\u06d2 \u0638\u0627\u06c1\u0631 \u06c1\u0648\u062a\u0627 \u06c1\u06d2 \u062c\u0633 \u0645\u06cc\u06ba \u0628\u0627\u0644\u063a\u0648\u06ba \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0648\u0631 \u0628\u0686\u0648\u06ba \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u06a9\u06cc \u067e\u0627\u0644\u06cc\u0633\u06cc\u0627\u06ba \u0634\u0627\u0645\u0644 \u06c1\u06cc\u06ba\u060c \u062c\u0648 \u0642\u0648\u0645\u06cc \u0627\u0648\u0631 \u0645\u0642\u0627\u0645\u06cc \u062a\u062d\u0641\u0638\u0627\u062a\u06cc \u0642\u0627\u0646\u0648\u0646 \u0633\u0627\u0632\u06cc \u0627\u0648\u0631 \u0631\u06c1\u0646\u0645\u0627\u0626\u06cc \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u062a\u06cc\u0627\u0631 \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06cc\u06ba\u06d4 \u0627\u0633 \u0645\u06cc\u06ba \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u06d2 \u0645\u0634\u062a\u0628\u06c1 \u0634\u06a9\u0627\u0631 \u06a9\u0648 \u067e\u06c1\u0686\u0627\u0646\u0646\u06d2 \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0631\u06c1\u0646\u0645\u0627\u0626\u06cc \u0634\u0627\u0645\u0644 \u06c1\u06d2\u06d4 \u06c1\u0645\u0627\u0631\u06cc \u062d\u0641\u0627\u0638\u062a \u06a9\u06cc \u062a\u0631\u0628\u06cc\u062a \u0645\u06cc\u06ba \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0633\u06d2 \u0645\u062a\u0639\u0644\u0642 \u0622\u06af\u0627\u06c1\u06cc \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0634\u0627\u0645\u0644 \u06c1\u06cc\u06ba\u06d4<\/p><p>\u00a0<\/p><p><strong>\u06c1\u0645\u0627\u0631\u06cc \u067e\u0631\u0648\u06a9\u06cc\u0648\u0631\u0645\u0646\u0679 \u0627\u0648\u0631 \u06c1\u0645\u0627\u0631\u06cc \u0633\u067e\u0644\u0627\u0626\u06cc \u0686\u06cc\u0646 \u0645\u06cc\u06ba \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u06a9\u0648 \u0631\u0648\u06a9\u0646\u0627<\/strong><\/p><p>\u0641\u0631\u0627\u06c1\u0645 \u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0645\u0639\u0627\u06c1\u062f\u06c1 \u06a9\u0631\u0646\u0627 LLR ICB \u06a9\u0627 \u0628\u0646\u06cc\u0627\u062f\u06cc \u06a9\u0627\u0645 \u06c1\u06d2\u06d4 \u06c1\u0645\u0627\u0631\u06cc \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0627 \u0637\u0631\u06cc\u0642\u06c1 \u06a9\u0631\u0627\u0624\u0646 \u06a9\u0645\u0631\u0634\u0644 \u0633\u0631\u0648\u0633 \u06a9\u06d2 \u0645\u0639\u06cc\u0627\u0631 \u06a9\u06cc \u067e\u06cc\u0631\u0648\u06cc \u06a9\u0631\u062a\u0627 \u06c1\u06d2\u06d4 \u0633\u0627\u0645\u0627\u0646 \u0627\u0648\u0631 \u062e\u062f\u0645\u0627\u062a \u06a9\u06cc \u062e\u0631\u06cc\u062f\u0627\u0631\u06cc \u06a9\u0631\u062a\u06d2 \u0648\u0642\u062a\u060c \u06c1\u0645 NHS \u0634\u0631\u0627\u0626\u0637 \u0648 \u0636\u0648\u0627\u0628\u0637 (\u0646\u0627\u0646 \u06a9\u0644\u06cc\u0646\u06cc\u06a9\u0644 \u067e\u0631\u0648\u06a9\u06cc\u0648\u0631\u0645\u0646\u0679 \u06a9\u06d2 \u0644\u06cc\u06d2) \u0627\u0648\u0631 NHS \u0633\u0679\u06cc\u0646\u0688\u0631\u0688 \u06a9\u0646\u0679\u0631\u06cc\u06a9\u0679 (\u06a9\u0644\u06cc\u0646\u06cc\u06a9\u0644 \u067e\u0631\u0648\u06a9\u06cc\u0648\u0631\u0645\u0646\u0679 \u06a9\u06d2 \u0644\u06cc\u06d2) \u0644\u0627\u06af\u0648 \u06a9\u0631\u062a\u06d2 \u06c1\u06cc\u06ba\u06d4 \u062f\u0648\u0646\u0648\u06ba \u06a9\u0648 \u0633\u067e\u0644\u0627\u0626\u0631\u0632 \u0633\u06d2 \u0645\u062a\u0639\u0644\u0642\u06c1 \u0642\u0627\u0646\u0648\u0646 \u0633\u0627\u0632\u06cc \u06a9\u06cc \u062a\u0639\u0645\u06cc\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0636\u0631\u0648\u0631\u062a \u06c1\u0648\u062a\u06cc \u06c1\u06d2\u06d4<\/p><p>\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u06cc\u06a9\u0679 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06d2 \u0648\u0636\u0627\u062d\u062a\u06cc \u0646\u0648\u0679 \u067e\u0631 \u062f\u0633\u062a\u06cc\u0627\u0628 \u06c1\u06cc\u06ba\u06d4 <a href=\"http:\/\/www.legislation.gov.uk\/ukpg5a\/2015\/30\/contents\/enacted\">http:\/\/www.legislation.gov.uk\/ukpg5a\/2015\/30\/contents\/enacted<\/a><\/p><p>\u06cc\u06c1 \u0636\u0631\u0648\u0631\u06cc \u06c1\u06d2 \u06a9\u06c1 \u06a9\u0627\u0631\u0648\u0628\u0627\u0631 \u0627\u067e\u0646\u06d2 \u0622\u067e\u0631\u06cc\u0634\u0646\u0632 \u0627\u0648\u0631 \u0633\u067e\u0644\u0627\u0626\u06cc \u0686\u06cc\u0646\u0632 \u0645\u06cc\u06ba \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u06a9\u06d2 \u062e\u0637\u0631\u0627\u062a \u06a9\u06cc \u0646\u0634\u0627\u0646\u062f\u06c1\u06cc \u0627\u0648\u0631 \u0627\u0646 \u0633\u06d2 \u0646\u0645\u0679\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0627\u067e\u0646\u06cc \u0633\u0631\u06af\u0631\u0645\u06cc\u0627\u06ba \u062c\u0627\u0631\u06cc \u0631\u06a9\u06be\u06cc\u06ba\u06d4 \u0645\u06a9\u0645\u0644 \u0631\u06c1\u0646\u0645\u0627\u0626\u06cc \u06cc\u06c1\u0627\u06ba \u0645\u0644 \u0633\u06a9\u062a\u06cc \u06c1\u06d2\u06d4 <a href=\"https:\/\/www.gov.uk\/government\/publications\/transparency-in-supply-chains-a-practical-guide\">\u0633\u067e\u0644\u0627\u0626\u06cc \u0686\u06cc\u0646\u0632 \u0645\u06cc\u06ba \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af: \u06a9\u0627\u0631\u0648\u0628\u0627\u0631 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0631\u06c1\u0646\u0645\u0627\u0626\u06cc - GOV.UK<\/a><\/p><p>\u00a0<\/p><p><strong>\u062a\u0627\u062b\u06cc\u0631 \u06a9\u0627 \u062c\u0627\u0626\u0632\u06c1<\/strong><\/p><p>\u06c1\u0645\u0627\u0631\u06cc \u0627\u067e\u0646\u06cc \u062a\u0646\u0638\u06cc\u0645 \u0627\u0648\u0631 \u0627\u067e\u0646\u06cc \u0633\u067e\u0644\u0627\u0626\u06cc \u0686\u06cc\u0646 \u0645\u06cc\u06ba \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u06d2 \u062e\u0637\u0631\u0627\u062a \u06a9\u06cc \u0646\u0634\u0627\u0646\u062f\u06c1\u06cc \u0627\u0648\u0631 \u0627\u0646 \u06a9\u0648 \u06a9\u0645 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0645 \u062f\u0631\u062c \u0630\u06cc\u0644 \u06a9\u0627\u0645 \u062c\u0627\u0631\u06cc \u0631\u06a9\u06be\u06cc\u06ba \u06af\u06d2\u06d4<\/p><ul><li>\u06c1\u0645 \u062c\u0633 \u0639\u0645\u0644\u06d2 \u06a9\u0648 \u0645\u0644\u0627\u0632\u0645\u062a \u062f\u06cc\u062a\u06d2 \u06c1\u06cc\u06ba \u0627\u0646 \u067e\u0631 \u0645\u0644\u0627\u0632\u0645\u062a \u0633\u06d2 \u067e\u06c1\u0644\u06d2 \u06a9\u06cc \u062c\u0627\u0646\u0686 \u0645\u06a9\u0645\u0644 \u06a9\u0631\u06cc\u06ba\u060c \u0627\u0646 \u06a9\u06cc \u0634\u0646\u0627\u062e\u062a \u0627\u0648\u0631 \u0628\u0631\u0637\u0627\u0646\u06cc\u06c1 \u0645\u06cc\u06ba \u06a9\u0627\u0645 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u062d\u0642 \u06a9\u06cc \u062a\u0635\u062f\u06cc\u0642 \u06a9\u0631\u06cc\u06ba\u06d4 \u06c1\u0645 \u06cc\u06c1 \u0628\u06be\u06cc \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u0626\u06cc\u06ba \u06af\u06d2 \u06a9\u06c1 \u0627\u06cc\u062c\u0646\u0633\u06cc\u0627\u06ba \u0645\u0646\u0638\u0648\u0631 \u0634\u062f\u06c1 \u0641\u0631\u06cc\u0645 \u0648\u0631\u06a9 \u067e\u0631 \u06c1\u06cc\u06ba\u06d4<\/li><li>\u062a\u0628\u062f\u06cc\u0644\u06cc \u06a9\u06cc \u0634\u0631\u0627\u0626\u0637 \u0648 \u0636\u0648\u0627\u0628\u0637 \u06a9\u06d2 \u0644\u06cc\u06d2 NHS \u0627\u06cc\u062c\u0646\u0688\u06d2 \u067e\u0631 \u0639\u0645\u0644 \u06a9\u0631\u06cc\u06ba \u062a\u0627\u06a9\u06c1 \u06cc\u06c1 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u06cc\u0627 \u062c\u0627 \u0633\u06a9\u06d2 \u06a9\u06c1 \u0639\u0645\u0644\u06d2 \u06a9\u0648 \u0645\u0646\u0635\u0641\u0627\u0646\u06c1 \u062a\u0646\u062e\u0648\u0627\u06c1 \u06a9\u06cc \u0634\u0631\u062d\u06cc\u06ba \u0627\u0648\u0631 \u0645\u0639\u0627\u06c1\u062f\u06d2 \u06a9\u06cc \u0634\u0631\u0627\u0626\u0637 \u0645\u0644\u06cc\u06ba\u06d4<\/li><li>\u0645\u0644\u0627\u0632\u0645\u062a \u06a9\u06cc \u0634\u0631\u0627\u0626\u0637 \u0648 \u0636\u0648\u0627\u0628\u0637 \u0645\u06cc\u06ba \u06a9\u0633\u06cc \u0628\u06be\u06cc \u0645\u062c\u0648\u0632\u06c1 \u062a\u0628\u062f\u06cc\u0644\u06cc \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u0679\u0631\u06cc\u0688 \u06cc\u0648\u0646\u06cc\u0646\u0648\u06ba \u0633\u06d2 \u0645\u0634\u0648\u0631\u06c1 \u06a9\u0631\u06cc\u06ba\u06d4<\/li><li>\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u0648 \u067e\u06c1\u0686\u0627\u0646\u0646\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u0633\u06d2 \u0646\u0645\u0679\u0646\u06d2 \u06a9\u06d2 \u0633\u0627\u062a\u06be \u0633\u0627\u062a\u06be \u0627\u0641\u0631\u0627\u062f \u067e\u0631 \u067e\u0691\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0627\u062b\u0631\u0627\u062a \u06a9\u0648 \u0633\u0645\u062c\u06be\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0639\u0644\u0645 \u0627\u0648\u0631 \u0645\u06c1\u0627\u0631\u062a \u062d\u0627\u0635\u0644 \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0645\u0627\u0631\u06d2 \u0639\u0645\u0644\u06d2 \u06a9\u06cc \u0645\u062f\u062f \u06a9\u0631\u06cc\u06ba\u06d4 \u0627\u0633 \u0628\u0627\u062a \u06a9\u0648 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u0626\u06cc\u06ba \u06a9\u06c1 NHS \u06a9\u06d2 \u0627\u0646\u062f\u0631 \u06a9\u0627\u0645 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u06c1\u0631 \u0641\u0631\u062f \u06a9\u0648 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u06d2 \u0645\u0645\u06a9\u0646\u06c1 \u0645\u0633\u062a\u0642\u0628\u0644 \u06a9\u06d2 \u0645\u062a\u0627\u062b\u0631\u06cc\u0646 \u06a9\u06cc \u0634\u0646\u0627\u062e\u062a \u06a9\u06d2 \u0644\u06cc\u06d2 \u0636\u0631\u0648\u0631\u06cc \u062a\u0631\u0628\u06cc\u062a \u0627\u0648\u0631 \u0622\u06af\u0627\u06c1\u06cc \u062d\u0627\u0635\u0644 \u06c1\u0648\u060c \u0627\u0646\u06c1\u06cc\u06ba \u0645\u062d\u0641\u0648\u0638 \u0631\u06a9\u06be\u0627 \u062c\u0627\u0626\u06d2\u06d4<\/li><li>\u06c1\u0645 \u0627\u0633 \u0628\u0627\u062a \u06a9\u0648 \u06cc\u0642\u06cc\u0646\u06cc \u0628\u0646\u0627\u0626\u06cc\u06ba \u06af\u06d2 \u06a9\u06c1 NHS \u06a9\u06d2 \u062a\u0645\u0627\u0645 \u0639\u0645\u0644\u06d2 \u06a9\u0648 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u0648\u06ba \u06a9\u06cc \u0634\u0646\u0627\u062e\u062a \u06a9\u06d2 \u0628\u0627\u0631\u06d2 \u0645\u06cc\u06ba \u062a\u0631\u0628\u06cc\u062a \u062a\u06a9 \u0631\u0633\u0627\u0626\u06cc \u062d\u0627\u0635\u0644 \u06c1\u0648\u06d4 \u0627\u0633 \u062a\u0631\u0628\u06cc\u062a \u0645\u06cc\u06ba \u062a\u0627\u0632\u06c1 \u062a\u0631\u06cc\u0646 \u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0634\u0627\u0645\u0644 \u06c1\u0648\u06ba \u06af\u06cc \u0627\u0648\u0631 \u0639\u0645\u0644\u06d2 \u06a9\u0648 \u0635\u062d\u062a \u06a9\u06cc \u062f\u06cc\u06a9\u06be \u0628\u06be\u0627\u0644 \u06a9\u06cc \u062e\u062f\u0645\u0627\u062a \u06a9\u0627 \u0633\u0627\u0645\u0646\u0627 \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0627\u0641\u0631\u0627\u062f \u06a9\u06cc \u0645\u062f\u062f \u06a9\u0631\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0646\u0631 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u0646\u06d2 \u0645\u06cc\u06ba \u0645\u062f\u062f \u0645\u0644\u06d2 \u06af\u06cc\u06d4<\/li><li>ICB \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u06a9\u0631\u0646\u06d2 \u0648\u0627\u0644\u06cc \u0679\u06cc\u0645 ICB \u06a9\u06d2 \u0633\u0627\u062a\u06be\u06cc\u0648\u06ba \u0627\u0648\u0631 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u06a9\u0648 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u06d2 \u0633\u0644\u0633\u0644\u06d2 \u0645\u06cc\u06ba \u0645\u0627\u06c1\u0631 \u0645\u0639\u0627\u0648\u0646\u062a \u0627\u0648\u0631 \u0645\u0634\u0648\u0631\u06c1 \u0641\u0631\u0627\u06c1\u0645 \u06a9\u0631\u062a\u06cc \u06c1\u06d2\u06d4<\/li><\/ul><p>\u00a0<\/p><ul><li>\u06c1\u0645\u0627\u0631\u06cc \u067e\u0627\u0631\u0679\u0646\u0631 \u062a\u0646\u0638\u06cc\u0645\u0648\u06ba \u0627\u0648\u0631 NHS \u06a9\u06cc \u0645\u0627\u0644\u06cc \u0627\u0639\u0627\u0646\u062a \u0633\u06d2 \u0686\u0644\u0646\u06d2 \u0648\u0627\u0644\u06cc \u062f\u06cc\u06af\u0631 \u062a\u0646\u0638\u06cc\u0645\u0648\u06ba \u06a9\u06d2 \u0633\u0627\u062a\u06be \u06a9\u0627\u0645 \u06a9\u0631\u06cc\u06ba \u062a\u0627\u06a9\u06c1 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u0648 \u0633\u0646\u062c\u06cc\u062f\u06af\u06cc \u0633\u06d2 \u0644\u06cc\u0627 \u062c\u0627\u0626\u06d2 \u0627\u0648\u0631 \u06a9\u0627\u0645 \u06a9\u06d2 \u0645\u0646\u0635\u0648\u0628\u0648\u06ba \u06a9\u06cc \u062d\u0641\u0627\u0638\u062a \u0645\u06cc\u06ba \u0646\u0645\u0627\u06cc\u0627\u06ba \u062e\u0635\u0648\u0635\u06cc\u0627\u062a \u06c1\u0648\u06ba\u06d4<\/li><\/ul><p>\u00a0<\/p><p>LLR ICB \u06af\u0648\u0631\u0646\u0646\u06af \u0628\u0627\u0688\u06cc \u0646\u06d2 \u0627\u0633 \u0628\u06cc\u0627\u0646 \u067e\u0631 \u063a\u0648\u0631 \u06a9\u06cc\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0627\u0633 \u06a9\u06cc \u0645\u0646\u0638\u0648\u0631\u06cc \u062f\u06cc \u06c1\u06d2 \u0642\u0627\u0646\u0648\u0646 \u0633\u0627\u0632\u06cc \u06a9\u06cc \u0636\u0631\u0648\u0631\u06cc\u0627\u062a \u06a9\u06cc \u062d\u0645\u0627\u06cc\u062a \u062c\u0627\u0631\u06cc \u0631\u06a9\u06be\u06d2 \u06af\u06cc\u06d4<\/p><p>\u06cc\u06c1 \u0628\u06cc\u0627\u0646 \u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc \u0627\u06cc\u06a9\u0679 2015 \u06a9\u06d2 \u0633\u06cc\u06a9\u0634\u0646 54(1) \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0628\u0646\u0627\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2 \u0627\u0648\u0631 31 \u0645\u0627\u0631\u0686 2026 \u06a9\u0648 \u062e\u062a\u0645 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u0645\u0627\u0644\u06cc \u0633\u0627\u0644 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06c1\u0645\u0627\u0631\u06cc \u063a\u0644\u0627\u0645\u06cc \u0627\u0648\u0631 \u0627\u0646\u0633\u0627\u0646\u06cc \u0627\u0633\u0645\u06af\u0644\u0646\u06af \u06a9\u06d2 \u0628\u06cc\u0627\u0646 \u06a9\u0648 \u062a\u0634\u06a9\u06cc\u0644 \u062f\u06cc\u062a\u0627 \u06c1\u06d2\u06d4<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Modern Slavery Act (2015) Statement 2025-26 Leicester, Leicestershire, and Rutland Integrated Care Board (ICB) Modern Slavery Act (2015) Statement 2025-26\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":22,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-7851","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>modern slavery - LLR ICB<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/modern-slavery-act-2015-statement-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"modern slavery - LLR ICB\" \/>\n<meta property=\"og:description\" content=\"Modern Slavery Act (2015) Statement 2025-26 Leicester, Leicestershire, and Rutland Integrated Care Board (ICB) Modern Slavery Act (2015) Statement 2025-26\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/modern-slavery-act-2015-statement-2\/\" \/>\n<meta property=\"og:site_name\" content=\"LLR ICB\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NHSLLR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T12:24:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NHS_LLR\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 \u0645\u0646\u0679\u0633\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/modern-slavery-act-2015-statement-2\\\/\",\"url\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/modern-slavery-act-2015-statement-2\\\/\",\"name\":\"modern slavery - LLR ICB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/#website\"},\"datePublished\":\"2023-02-22T16:36:00+00:00\",\"dateModified\":\"2025-03-20T12:24:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/modern-slavery-act-2015-statement-2\\\/#breadcrumb\"},\"inLanguage\":\"ur\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/modern-slavery-act-2015-statement-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/modern-slavery-act-2015-statement-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"modern slavery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/#website\",\"url\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/\",\"name\":\"LLR ICB\",\"description\":\"LLR Integrated Care Board\",\"publisher\":{\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ur\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/#organization\",\"name\":\"LLR ICB\",\"url\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ur\",\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/New-Project-4.jpg?fit=452%2C93&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/New-Project-4.jpg?fit=452%2C93&ssl=1\",\"width\":452,\"height\":93,\"caption\":\"LLR ICB\"},\"image\":{\"@id\":\"https:\\\/\\\/leicesterleicestershireandrutland.icb.nhs.uk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NHSLLR\",\"https:\\\/\\\/x.com\\\/NHS_LLR\",\"https:\\\/\\\/www.instagram.com\\\/nhsllr\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc - LLR ICB","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/modern-slavery-act-2015-statement-2\/","og_locale":"en_US","og_type":"article","og_title":"modern slavery - LLR ICB","og_description":"Modern Slavery Act (2015) Statement 2025-26 Leicester, Leicestershire, and Rutland Integrated Care Board (ICB) Modern Slavery Act (2015) Statement 2025-26\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 [&hellip;]","og_url":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/modern-slavery-act-2015-statement-2\/","og_site_name":"LLR ICB","article_publisher":"https:\/\/www.facebook.com\/NHSLLR","article_modified_time":"2025-03-20T12:24:04+00:00","twitter_card":"summary_large_image","twitter_site":"@NHS_LLR","twitter_misc":{"Est. reading time":"4 \u0645\u0646\u0679\u0633"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/modern-slavery-act-2015-statement-2\/","url":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/modern-slavery-act-2015-statement-2\/","name":"\u062c\u062f\u06cc\u062f \u063a\u0644\u0627\u0645\u06cc - LLR ICB","isPartOf":{"@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/#website"},"datePublished":"2023-02-22T16:36:00+00:00","dateModified":"2025-03-20T12:24:04+00:00","breadcrumb":{"@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/modern-slavery-act-2015-statement-2\/#breadcrumb"},"inLanguage":"ur","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/modern-slavery-act-2015-statement-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/modern-slavery-act-2015-statement-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/"},{"@type":"ListItem","position":2,"name":"modern slavery"}]},{"@type":"WebSite","@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/#website","url":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/","name":"\u0627\u06cc\u0644 \u0627\u06cc\u0644 \u0622\u0631 \u0622\u0626\u06cc \u0633\u06cc \u0628\u06cc","description":"\u0627\u06cc\u0644 \u0627\u06cc\u0644 \u0622\u0631 \u0627\u0646\u0679\u06cc\u06af\u0631\u06cc\u0679\u0688 \u06a9\u06cc\u0626\u0631 \u0628\u0648\u0631\u0688","publisher":{"@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ur"},{"@type":"Organization","@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/#organization","name":"\u0627\u06cc\u0644 \u0627\u06cc\u0644 \u0622\u0631 \u0622\u0626\u06cc \u0633\u06cc \u0628\u06cc","url":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/","logo":{"@type":"ImageObject","inLanguage":"ur","@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/leicesterleicestershireandrutland.icb.nhs.uk\/wp-content\/uploads\/2022\/06\/New-Project-4.jpg?fit=452%2C93&ssl=1","contentUrl":"https:\/\/i0.wp.com\/leicesterleicestershireandrutland.icb.nhs.uk\/wp-content\/uploads\/2022\/06\/New-Project-4.jpg?fit=452%2C93&ssl=1","width":452,"height":93,"caption":"LLR ICB"},"image":{"@id":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NHSLLR","https:\/\/x.com\/NHS_LLR","https:\/\/www.instagram.com\/nhsllr\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/wp-json\/wp\/v2\/pages\/7851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/wp-json\/wp\/v2\/comments?post=7851"}],"version-history":[{"count":26,"href":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/wp-json\/wp\/v2\/pages\/7851\/revisions"}],"predecessor-version":[{"id":22128,"href":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/wp-json\/wp\/v2\/pages\/7851\/revisions\/22128"}],"wp:attachment":[{"href":"https:\/\/leicesterleicestershireandrutland.icb.nhs.uk\/ur\/wp-json\/wp\/v2\/media?parent=7851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}